{"id":2728,"date":"2015-06-18T14:03:54","date_gmt":"2015-06-18T14:03:54","guid":{"rendered":"http:\/\/www.policyresearchnetwork.ca\/?p=2728"},"modified":"2015-06-18T14:05:01","modified_gmt":"2015-06-18T14:05:01","slug":"amanda-k-slaunwhite","status":"publish","type":"post","link":"http:\/\/www.policyresearchnetwork.ca\/fr\/amanda-k-slaunwhite\/","title":{"rendered":"Amanda K Slaunwhite"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.policyresearchnetwork.ca\/wp-content\/uploads\/2015\/06\/Amanda-K.-Slaunwhite.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-2729 alignleft\" src=\"http:\/\/www.policyresearchnetwork.ca\/wp-content\/uploads\/2015\/06\/Amanda-K.-Slaunwhite-198x300.jpg\" alt=\"\" width=\"198\" height=\"300\" srcset=\"http:\/\/www.policyresearchnetwork.ca\/wp-content\/uploads\/2015\/06\/Amanda-K.-Slaunwhite-198x300.jpg 198w, http:\/\/www.policyresearchnetwork.ca\/wp-content\/uploads\/2015\/06\/Amanda-K.-Slaunwhite-99x150.jpg 99w, http:\/\/www.policyresearchnetwork.ca\/wp-content\/uploads\/2015\/06\/Amanda-K.-Slaunwhite.jpg 633w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/a>1. Quel poste occupez-vous pr\u00e9sentement et quel est votre titre officiel?<\/strong><\/p>\n<p>Je suis boursi\u00e8re de recherches postdoctorales au d\u00e9partement de sociologie de University of New Brunswick, \u00e0 Fredericton. Mon programme de recherche est financ\u00e9 par une bourse \u00e9tudiante salariale en recherche de la Fondation de la recherche en sant\u00e9 du Nouveau-Brunswick \u2013 IRSC-SRAP-USSM. Je travaille \u00e9galement avec le Centre for Addictions Research de la Colombie-Britannique en tant que collaboratrice scientifique.<\/p>\n<p><strong style=\"line-height: 1.5;\">2. Quelle formation avez-vous re\u00e7ue?<\/strong><\/p>\n<p>Je suis originaire d\u2019une r\u00e9gion rurale situ\u00e9e juste \u00e0 l\u2019ext\u00e9rieur d\u2019Halifax et je me suis r\u00e9cemment install\u00e9e au Nouveau-Brunswick apr\u00e8s avoir fait mon doctorat en g\u00e9ographie de la sant\u00e9 en Colombie-Britannique, \u00e0 University of Victoria. J\u2019ai une ma\u00eetrise en am\u00e9nagement urbain et r\u00e9gional de Queen\u2019s University et un baccalaur\u00e9at en science politique de Dalhousie University. Pendant mes \u00e9tudes ou entre mes dipl\u00f4mes, j\u2019ai travaill\u00e9 dans le secteur public pour des organismes comme le Parlement du Canada, la Commission de la sant\u00e9 mentale du Canada, Centraide du Grand Victoria et le minist\u00e8re de la Sant\u00e9 de la Colombie-Britannique.<\/p>\n<p><strong style=\"line-height: 1.5;\">3. Parlez-nous un peu de votre parcours professionnel. D\u2019o\u00f9 vient votre passion pour la recherche ou le travail que vous faites et comment s\u2019est-elle d\u00e9velopp\u00e9e?<\/strong><\/p>\n<p>J\u2019ai suivi un parcours de carri\u00e8re non conventionnel pour en arriver o\u00f9 je suis. Mes dipl\u00f4mes sont tous ax\u00e9s sur des disciplines diff\u00e9rentes, mais compl\u00e9mentaires (science politique, am\u00e9nagement urbain et g\u00e9ographie), et j\u2019ai pris du temps entre mes dipl\u00f4mes pour travailler dans le secteur public. Je m\u2019int\u00e9resse depuis toujours \u00e0 la politique sur les soins de sant\u00e9, et c\u2019est au cours de mon stage au Service d\u2019information et de recherche parlementaires que je me suis int\u00e9ress\u00e9e aux possibilit\u00e9s de recherche li\u00e9es aux soins de sant\u00e9 mentale. J\u2019ai trouv\u00e9 particuli\u00e8rement inspirant de d\u00e9couvrir les exp\u00e9riences des patients et des fournisseurs de services qui aident les personnes aux prises avec des troubles de sant\u00e9 mentale, et ces histoires continuent \u00e0 me motiver \u00e0 travailler dans ce domaine.<\/p>\n<p><strong style=\"line-height: 1.5;\">4. Parlez-nous d\u2019un ou deux de vos projets actuels.<\/strong><\/p>\n<p>Je suis tr\u00e8s enthousiaste \u00e0 l\u2019id\u00e9e d\u2019entreprendre plusieurs projets destin\u00e9s \u00e0 mieux comprendre l\u2019acc\u00e8s aux soins de sant\u00e9 des jeunes, des adultes et des personnes des r\u00e9gions rurales et \u00e9loign\u00e9es du Nouveau-Brunswick, de m\u00eame que l\u2019utilisation qu\u2019ils font de ces soins. Un de mes premiers projets utilisera des donn\u00e9es administratives sur la sant\u00e9 pour examiner l\u2019hospitalisation des jeunes pour des raisons de sant\u00e9 mentale au Nouveau-Brunswick sur une p\u00e9riode de 12 ans et un autre \u00e9valuera les r\u00e9percussions de la fermeture d\u2019h\u00f4pitaux ruraux en 2006-2007 sur l\u2019acc\u00e8s aux services et sur l\u2019\u00e9tat de sant\u00e9. J\u2019ai le privil\u00e8ge \u00e9galement de travailler avec une \u00e9quipe des quatre provinces de l\u2019Atlantique au projet ACCESS-Mental Health (cheminement du patient). Plus tard cet \u00e9t\u00e9, nous m\u00e8nerons des entrevues partout au Nouveau-Brunswick aupr\u00e8s de jeunes, de parents et de fournisseurs de services qui viennent en aide aux jeunes aux prises avec des troubles de sant\u00e9 mentale.<\/p>\n<p><strong style=\"line-height: 1.5;\">5. Comment vos recherches ou votre travail peuvent-ils contribuer, selon vous, \u00e0 l\u2019\u00e9laboration de politiques publiques fond\u00e9es sur des donn\u00e9es probantes?<\/strong><\/p>\n<p>J\u2019ai toujours cherch\u00e9 \u00e0 \u00e9laborer des projets de recherche appliqu\u00e9e en sant\u00e9 qui peuvent servir \u00e0 guider la r\u00e9forme des soins de sant\u00e9. Il y a beaucoup de choses que nous ne savons pas sur la fa\u00e7on dont les Canadiens ont acc\u00e8s aux services. Ces choses pourraient servir \u00e0 mieux concevoir les traitements et l\u2019acc\u00e8s aux soins et, dans de nombreux cas, \u00e0 r\u00e9duire la demande de ressources des soins actifs et \u00e0 am\u00e9liorer le continuum et la qualit\u00e9 des soins. Mon travail \u00e0 University of New Brunswick vise \u00e0 combler les lacunes en mati\u00e8re de connaissances dans deux domaines qui, \u00e0 mon avis, sont particuli\u00e8rement pr\u00e9occupants en ce moment au Nouveau-Brunswick\u00a0: les jeunes aux prises avec des troubles de sant\u00e9 mentale et l\u2019acc\u00e8s aux soins des communaut\u00e9s rurales.<\/p>\n<p><strong style=\"line-height: 1.5;\">6. D\u00e9crivez-nous certaines de vos r\u00e9alisations pass\u00e9es qui ont \u00e9t\u00e9 importantes dans votre cheminement professionnel. Ont-elles contribu\u00e9 \u00e0 promouvoir des politiques publiques fond\u00e9es sur des donn\u00e9es probantes?<\/strong><\/p>\n<p>Depuis quelques ann\u00e9es, je fais du b\u00e9n\u00e9volat aupr\u00e8s de personnes ayant une exp\u00e9rience v\u00e9cue. Me joindre au vaste r\u00e9seau de patients, de fournisseurs de services et de personnes soignantes de partout au Canada qui cherche \u00e0 am\u00e9liorer les services de sant\u00e9 mentale \u00e0 l\u2019\u00e9chelle du pays a \u00e9t\u00e9 une source d\u2019inspiration et de formation. Cela est tr\u00e8s enrichissant, en plus d\u2019\u00eatre utile pour d\u00e9couvrir ce qui se passe ailleurs.<\/p>\n<p><strong style=\"line-height: 1.5;\">7. D\u00e9crivez en quelques phrases comment vous avez particip\u00e9 aux activit\u00e9s du RRPSNB et comment votre relation avec le R\u00e9seau a contribu\u00e9 \u00e0 votre travail ou \u00e0 vos recherches et\/ou aux politiques sociales\/\u00e9conomiques.<\/strong><\/p>\n<p>Le RRPSNB a \u00e9t\u00e9 pour nous une excellente ressource pour planifier nos projets et \u00e9tablir des liens avec les organismes communautaires de partout dans la province. La participation des patients et des fournisseurs de services est tr\u00e8s importante pour le succ\u00e8s de nos projets de recherche, et nous sommes ravis de pouvoir avoir recours \u00e0 l\u2019expertise du RRPSNB pour \u00e9laborer, mettre en \u0153uvre et am\u00e9liorer les strat\u00e9gies que nous utilisons pour recruter des participants \u00e0 nos activit\u00e9s de recherche, par exemple le projet sur le cheminement du patient.<\/p>\n<p><strong style=\"line-height: 1.5;\">8. Auriez-<\/strong><strong style=\"line-height: 1.5;\">vous quelque chose \u00e0 ajouter, un mot de la fin?<\/strong><\/p>\n<p>C\u2019est merveilleux d\u2019\u00eatre de retour dans les Maritimes, surtout maintenant que l\u2019hiver est termin\u00e9. Je suis constamment \u00e9tonn\u00e9e par la beaut\u00e9 du Nouveau-Brunswick; les r\u00e9gions rurales en particulier sont tr\u00e8s charmantes. J\u2019ai mang\u00e9 le meilleur poisson-frites de ma vie juste \u00e0 l\u2019ext\u00e9rieur de Springfield et j\u2019ai tr\u00e8s h\u00e2te d\u2019aller faire du camping dans l\u2019\u00eele Deer plus tard cet \u00e9t\u00e9.<\/p>","protected":false},"excerpt":{"rendered":"<p>1. Quel poste occupez-vous pr\u00e9sentement et quel est votre titre officiel? Je suis boursi\u00e8re de recherches postdoctorales [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-member-spotlight"],"_links":{"self":[{"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/posts\/2728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/comments?post=2728"}],"version-history":[{"count":0,"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/posts\/2728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/media\/2729"}],"wp:attachment":[{"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/media?parent=2728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/categories?post=2728"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.policyresearchnetwork.ca\/fr\/wp-json\/wp\/v2\/tags?post=2728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}